{"id":13583,"date":"2023-03-05T17:16:17","date_gmt":"2023-03-05T16:16:17","guid":{"rendered":"https:\/\/www.pfarregersthof.at\/komm\/?p=13583"},"modified":"2023-03-05T17:16:18","modified_gmt":"2023-03-05T16:16:18","slug":"osterkerzen-zeichen-fuer-neues-leben-17-3","status":"publish","type":"post","link":"https:\/\/www.pfarregersthof.at\/komm\/2023\/03\/osterkerzen-zeichen-fuer-neues-leben-17-3\/","title":{"rendered":"Osterkerzen &#8211; Zeichen f\u00fcr neues Leben (17.3.)"},"content":{"rendered":"\n<p>Osterkerzen begleiten uns durch das ganze Jahr, deshalb wollen wir wieder Kerzen verzieren, damit sich auch in den kommenden Monaten diese gute Botschaft des Osterfestes in unserer Gemeinde verbreitet.<\/p>\n<p>Eine herzliche Einladung zum gemeinsamen <strong>Basteln<\/strong> am <strong>17. M\u00e4rz 2023 ab 15.00 Uhr im Besprechungszimmer im Pfarrhaus<\/strong>. Jede und jeder kann kommen und mithelfen, so lange oder kurz man m\u00f6chte. Material ist vorhanden. Wir freuen uns! Gerne nehmen wir auch Unterst\u00fctzung an beim Verkaufen der Kerzen ab Palmsonntag bis Ostern.<\/p>\n<p><span style=\"color: #3366ff;\"><em>Hemma Gamillscheg<\/em><\/span> mit Team<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Osterkerzen begleiten uns durch das ganze Jahr, deshalb wollen wir wieder Kerzen verzieren, damit sich auch in den kommenden Monaten diese gute Botschaft des Osterfestes in unserer Gemeinde verbreitet. Eine herzliche Einladung zum gemeinsamen Basteln am 17. M\u00e4rz 2023 ab 15.00 Uhr im Besprechungszimmer im Pfarrhaus. Jede und jeder kann kommen und mithelfen, so lange [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-13583","post","type-post","status-publish","format-standard","category-archiv"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 23:58:57","action":"category","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/posts\/13583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/comments?post=13583"}],"version-history":[{"count":1,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/posts\/13583\/revisions"}],"predecessor-version":[{"id":13584,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/posts\/13583\/revisions\/13584"}],"wp:attachment":[{"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/media?parent=13583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/categories?post=13583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/tags?post=13583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}