{"id":4274,"date":"2017-01-03T17:05:53","date_gmt":"2017-01-03T16:05:53","guid":{"rendered":"http:\/\/www.pfarregersthof.at\/komm\/?p=4274"},"modified":"2017-01-03T17:09:14","modified_gmt":"2017-01-03T16:09:14","slug":"ansprache-jahresschluss-gottesdienst","status":"publish","type":"post","link":"https:\/\/www.pfarregersthof.at\/komm\/2017\/01\/ansprache-jahresschluss-gottesdienst\/","title":{"rendered":"Ansprache Jahresschluss-Gottesdienst"},"content":{"rendered":"<p><em>Ansprache von Univ.Prof. Dr. Regina Polak im Jahresschluss-Gottesdienst am 31.12.2016 in der Pfarrkirche.<\/em><\/p>\n<h2>Flucht und Migration: Ort, um Hoffnung zu lernen<\/h2>\n<p>Ich danke f\u00fcr die Einladung, Gedanken zum Jahresabschluss formulieren zu d\u00fcrfen.<\/p>\n<p>Was sagt man am Ende eines weltweit schwierigen Jahres \u2013 zumal im Wissen, dass uns die kommenden Jahrzehnte vor unz\u00e4hlige Herausforderungen stellen werden?<\/p>\n<p>Ich habe mich entschieden, \u00fcber die Hoffnung zu sprechen \u2013 jene gelehrte, gebildete Hoffnung, wie wir sie aus der Bibel und innerhalb unseres christlichen Glaubens <strong>lernen<\/strong> k\u00f6nnen. Denn aus christlicher Sicht l\u00e4sst sich Hoffnung <strong>LERNEN<\/strong>, ist etwas Emotionales, aber ganz wesentlich auch etwas <strong>Mentales<\/strong> und eminent <strong>Praktisches<\/strong>. Und es ist ja nach&nbsp; 1&nbsp; Petr 3,15 auch die <strong>HOFFNUNG<\/strong>, \u00fcber die wir jedem Rede und Antwort stehen sollen \u2013 insbesondere wenn wir um der Gerechtigkeit willen leiden.<\/p>\n<p>Dazu werde ich von jenem Thema ausgehen, das Europa sp\u00e4testens seit dem Herbst 2015 intensiv besch\u00e4ftigt: Flucht und Migration. Ich halte diese globale Herausforderung f\u00fcr eine Situation, in der Hoffnung gelernt werden kann.<\/p>\n<p>Am 19. April dieses Jahres sagte Papst Franziskus zu den Fl\u00fcchtlingen auf Lesbos: \u201eIhr werdet als Problem behandelt und seid in Wirklichkeit ein Geschenk!\u201c<\/p>\n<p>Ist das nicht ziemlich naiv \u2013 angesichts der nicht zu leugnenden Schwierigkeiten rund um Integration, politischen Islamismus und Terror sogar schlichtweg abwegig und gef\u00e4hrlich?<\/p>\n<p>Man kann diesen Satz vermutlich nur verstehen, wenn man die theologische Bedeutung kennt, die Flucht und Migration, Exil und Diaspora, das Verhalten gegen\u00fcber Fremden in der kirchlichen Lehre und in der Heiligen Schrift haben. Papst Franziskus steht mit seiner Einsch\u00e4tzung in einer langen Tradition.<\/p>\n<p>Zun\u00e4chst das kirchliche Lehramt.<\/p>\n<p>In der Instruktion des P\u00e4pstlichen Rats der Seelsorge f\u00fcr Migranten und Menschen unterwegs \u201eErga migrantes Caritas Christi\u201c (Die Liebe Christi zu den Migranten) werden die internationalen Migrationen der Gegenwart als \u201eZeichen der Zeit\u201c bezeichnet, also als Wirklichkeit, die mit den Augen und Ohren des Glaubens betrachtet, eine M\u00f6glichkeit darstellen, heute Gottes Pr\u00e4senz, seinen Zuspruch, aber auch seinen Anspruch zu erkennen. Das Dokument spricht in diesem Zusammenhang von einer Herausforderung, die es beim Aufbau einer erneuerten Menschheit und in der Verk\u00fcndigung des Friedens zu entdecken und zu sch\u00e4tzen gilt.\u201c<\/p>\n<p>Die Migrationen fordern uns also auf, an der Erneuerung der Menschheit mitzuwirken und in Wort und Tat den Frieden zu verk\u00fcndigen. Indem wir das tun, k\u00f6nnen wir Gott wahrnehmen.<\/p>\n<p>An anderer Stelle ist zu lesen: \u201eDer \u00dcbergang von monokulturellen zu multikulturellen Gesellschaften kann sich so als Zeichen der lebendigen Gegenwart Gottes in der Geschichte und in der Gemeinschaft der Menschen erweisen, da er eine g\u00fcnstige Gelegenheit bietet, den Plan Gottes einer universalen Gemeinschaft zu verwirklichen.\u201c<\/p>\n<p>Was f\u00fcr eine Hoffnung: Indem unserer Gesellschaften durch Migration religi\u00f6s und kulturell vielf\u00e4ltiger werden, k\u00f6nnen wir dem lebendigen Gott selbst begegnen.<\/p>\n<p>Freilich nur, wenn wir selbst die Gelegenheit n\u00fctzen, am Aufbau einer universalen Gemeinschaft mitzuwirken. Dies ist die immense Aufgabe, die ansteht: zu lernen, was es bedeutet, in all unserer Verschiedenheit eine Menschheit zu sein; zu lernen, was Gerechtigkeit bedeutet.<\/p>\n<p>Dass dies keinesfalls einfach ist, wei\u00df der P\u00e4pstliche Migranten-Rat durchaus: \u201eGleichzeitig aber wirft das Ph\u00e4nomen der Migration eine regelrecht ethische Frage auf, n\u00e4mlich die Frage nach einer neuen internationalen Wirtschaftsordnung f\u00fcr eine gerechtere Verteilung der G\u00fcter der Erde (\u2026) Daraus ergibt sich auch die Notwendigkeit eines wirksameren Einsatzes zur Realisierung von Bildungs- und Pastoralsystemen im Hinblick auf eine Erziehung zu einer \u201emondialen Sicht\u201c, das hei\u00dft zu einer Sicht der Weltgemeinschaft, die als eine Familie von V\u00f6lkern angesehen wird, der schlie\u00dflich im Blick auf das universale Gemeinwohl die G\u00fcter der Erde zustehen.\u201c<\/p>\n<p>Migration wird also als Symptom gesehen \u2013 als Folge einer ungerechten internationalen Wirtschaftsordnung. Erg\u00e4nzen m\u00fcsste man noch: als Folge von Exklusionsprozessen, die weltweit Menschen f\u00fcr den \u00f6konomischen Prozess \u00fcberfl\u00fcssig machen; als Folge von Kriegen, die auch Nachwirkungen des europ\u00e4ischen Kolonialismus und der amerikanischen Politik der vergangenen beiden Jahrhunderte sind; nicht zuletzt als Folge des Kliamwandels.<\/p>\n<p>Was soll daran Anlass zur Hoffnung geben?<\/p>\n<p>Nun: Ganz praktisch zwingen uns Fl\u00fcchtlinge und Migranten dazu, all diese Probleme und Herausforderungen, um die man in Wissenschaft und Politik schon lange wei\u00df, endlich anzugehen \u2013 hoffentlich noch zeitgerecht. Migration kann auch gesehen werden als Spiegel, als Seh-Hilfe, die uns hilft, nach den Ursachen der Migrationen zu fragen und unseren Anteil daran, aber auch unsere Handlungs-M\u00f6glichkeiten zu identifizieren. Migration weckt uns gleichsam auf \u2013 zweifellos etwas unsanft. Aber das kann auch Hoffnung geben.<\/p>\n<p>Die tiefere, wesentlicher Hoffnung l\u00e4sst sich freilich in den biblischen Erz\u00e4hlungen finden,&nbsp; auf die sich auch Erga migrantes bezieht.<\/p>\n<p>Denn der ethische Monotheismus der Heiligen Schrift wurde wesentlich Erfahrungen im Kontext von Flucht und Migration abgerungen.<\/p>\n<p>Flucht aus \u00c4gypten, 40 Jahre W\u00fcstenwanderung, Vertreibung aus der Heimat und Exil in Babylon: F\u00fcr die Verfasser zentraler Texte des Alten Testaments sind alle diese Erfahrungen zun\u00e4chst eine Katastrophe. Aber \u2013 und das scheint mir mit Israel einzigartig in die Geschichte Eingang gefunden haben \u2013 diese Erfahrungen werden als Lernort genutzt. Geanu das k\u00f6nnen und sollen wir jetzt auch tun: An den Herausforderungen lernen.<\/p>\n<p>Die biblischen Migranten lernen, wie der Fluch der Migration zum Segen werden kann. Aus den katastrophalen Erfahrungen werden spirituelle, ethische und politische Konsequenzen gezogen; Wenn wir solche Katartiohen zuk\u00fcnftig verhindern wollen, braucht es Rechte Gottesverehrung und eine soziale Gerechtigkeitspraxis, ein hohes soziales Ethos und denAufbau einer gerechten Gesellschaft ohne Arme. Weiters die Verpflichtung, die eigene Geschichte nicht zu vergessen, T\u00e4ter wie Opfer beim Namen zu nennen, und sich durch Erinnerung und Lernen immer wieder aufs Neue dieser Erfahrungen zu vergewissern. All die soll Zusammenleben und Frieden sichern.<\/p>\n<p>Statt die Ereignisse mit religi\u00f6sem Vokabular zu legitimieren, weg- oder sch\u00f6nzureden, ziehen die Verfasser der Texte handfeste praktische Konsequenzen aus ihren&nbsp; Erfahrungen: Wir brauchen Feste und Feiern des Erinnerns und Lernens. Wir brauchen eine Liturgie, die uns hilft, Gott zu verehren. Wir brauchen ein Recht und Gesetze, die Armut verhindern und die Schw\u00e4chsten der Gesellschaft sowie die Fremden sch\u00fctzen. Das Alte Testament erz\u00e4hlt, wie dies gelernt und konkret umgesetzt wird. Als treuer Begleiter in diesen Lern- und Erkenntnisprozesses wird Gott selbst erkannt. Gott wird erfahren als jene Wirklichkeit, die&nbsp; aus dieser Katastrophe befreit.<\/p>\n<p>Von daher pr\u00e4gt Migration die Wirklichkeitsdeutung der Schrift bereits in der Genesis, als eine&nbsp; Art&nbsp; Matrix,&nbsp; in&nbsp; die&nbsp; Gottes&nbsp; Offenbarung&nbsp; eingeschrieben&nbsp; wird.&nbsp;&nbsp; Die&nbsp; Geschichte der Menschheit beginnt mit der Vertreibung aus dem Paradies, verbunden mit der F\u00e4higkeit Gut und B\u00f6se unterscheiden zu k\u00f6nnen \u2013 und zu m\u00fcssen. Mensch-Sein hei\u00dft vertrieben sein. Kain \u201egeht sodann weg vom Herrn\u201c (Gen 4,16) \u2013 und je mehr sich die Nachfahren Kains vom Garten Eden entfernen, umso gr\u00f6\u00dfer werden Gewalt und S\u00fcnde. Der \u201eNeustart\u201c der&nbsp; Sch\u00f6pfung nach der Sintflut beginnt mit der Auswanderung Noahs. Abraham muss seine Heimat verlassen, um zum Segen f\u00fcr alle V\u00f6lker werden zu k\u00f6nnen. Sein Urenkel Josef&nbsp; macht als Zuwanderer Karriere am K\u00f6nigshof \u00c4gyptens, bis die Nachkommen den Pharaonen unheimlich und versklavt werden. Aufbruch, Flucht, Vertreibung, Erfahrungen von Fremdheit ohne Ende.<\/p>\n<p>Kann es sein, dass Migrationserfahrungen in besonderer Weise geeignet sind, f\u00fcr die Wahrnehmung der Pr\u00e4senz Gottes zu sensibilisieren? Sind die dabei gewonnenen theologischen Einsichten in besonderer Weise belastbar, tragf\u00e4hig und nachhaltig?<\/p>\n<p>Die Erz\u00e4hlung von Moses, der von \u00c4gypten nach Midian ins Exil fl\u00fcchten musste, weil er einen \u00e4gyptischen Aufseher erschlagen hatte, legt dies nahe: Im Exil offenbart der Gott, der auch der unsere ist, seinen Namen. JHWH, zumeist \u00fcbersetzt mit Ich bin der, der ich ich bin; der ich sein werde; ich bin da. Der franz\u00f6sische Jesuit und Theologe Michel de Certeau \u00fcbersetzt das Tetragramm, das ja ein Zeitwort ist, pointiert mit: \u201eIch habe keinen Namen als das, was Dich aufbrechen l\u00e4sst.\u201c JHWH \u2013 der Name des Herrn, verweist auf lautere Pr\u00e4senz, auf Ver\u00e4nderung, auf Aufbruch.<\/p>\n<p>Was bedeutet dieser Name f\u00fcr uns in \u00d6sterreich im Kontext von Migration und Flucht?<\/p>\n<p>Erfahrungen von Ohnmacht und Hoffnungslosigkeit, von Ausgeliefertsein und Abh\u00e4ngigkeit, von Fremdheit und Nicht-Zugeh\u00f6rigkeit sind nicht notwendig an Flucht und Migration gebunden. Aber sie k\u00f6nnen sichtlich dabei helfen, sich f\u00fcr die Frage nach Gott zu \u00f6ffnen und auf ihn h\u00f6ren zu lernen. In diesem Sinn k\u00f6nnen auch wir Se\u00dfhafte uns an diesen Namen&nbsp; Gottes erinnern und auf ihn unsere Hoffnung setzen. Er hat sein Volk schon so oft aus der Katastrophe geholt. Er wird es wieder tun, wenn wir auf ihn h\u00f6ren lernen. Biblisch betrachtet sind katastrophische Situationen der zentrale Ort, an dem Hoffnung gelernt wird. Diese Dynamik hat aber Voraussetzungen, damit sie sich entfalten kann. Sie verlangt wahrhaftige und n\u00fcchterne Selbstwahrnehmung, Selbstkritik und die Bereitschaft zu Umkehr und Reue: Was haben wir zu unserer Situation beigetragen? Was m\u00fcssen wir ver\u00e4ndern? So hat das Migrantenvolk Israel glauben gelernt, so k\u00f6nnen es auch wir lernen.<\/p>\n<p>Die Gemeinden der Schriften des Neuen Testaments lebten zwar nicht mehr als Fl\u00fcchtlinge und Migranten, aber auch ihre Lebenssituationen waren katastrophal. Nicht wenige Familien in den Gemeinden waren Opfer der Massenkreuzigungen der Gewaltherrschaft des Imperium Romanum; mit der Zerst\u00f6rung des Tempels in Jerusalem hatten auch Judenchristen ihr kultisches Zentrum und damit ihre Hoffnungen verloren; in der heidnischen Welt erlebten sie sich als Fremdk\u00f6rper. In dieser Situation wird nun erneut auf jene Narrative der Tradition zur\u00fcckgegriffen, die schon mehrfach dabei geholfen haben, in verzweifelten Situationen Sinn und Hoffnung zu sch\u00f6pfen: Narrative, die im Kontext von Migrationserfahrungen entstanden sind.<\/p>\n<p>Wie sehr die fr\u00fchen Christen ihre Lebenssituation mittels migrantischer Hermeneutik interpretiert haben, lassen viele Texte des Neuen Testaments erkennen. So l\u00e4sst Lukas das Leben des Jesus von Nazareth an der sozialen Peripherie einer fremden Stadt beginnen. Die religi\u00f6se und soziale Ver\u00e4nderung beginnt nicht im politischen und religi\u00f6sen Zentrum der Macht, sondern an dessen Rand. Das Motiv von Jesu Geburt in Bethlehem, sein Leben in Galil\u00e4a \u2013 also am Land bei den einfachen, armen Leuten \u2013 f\u00fchrt die Erfahrungen Israels mit einem Gott auf der Seite der Marginalisierten konsequent weiter. Jesus verk\u00fcndet seine Botschaft als Wanderprediger in Galil\u00e4a und wird als Heimatloser beschrieben (Lk 9,58). Matth\u00e4us wiederum greift \u2013 siehe heute &#8211;&nbsp; auf das Motiv der Flucht nach \u00c4gypten zur\u00fcck,&nbsp; aus dem auch Jesus geholt werden muss (Mt 2, 13-15). Damit wird nicht nur best\u00e4tigt, dass Jesus zuinnerst mit Israel verbunden ist, auch die Parallele mit Moses ist offenkundig. Zugleich kann \u00c4gypten so zum Ort m\u00f6glicher Befreiung werden. Erneut wird an einem Migranten Gottes Wirken erkennbar.<\/p>\n<p>Die Heimatlosigkeit des Jesus von Nazareth wird auch f\u00fcr seine J\u00fcnger zur Verpflichtung und Voraussetzung, um das Reich Gottes verk\u00fcnden k\u00f6nnen. Das Selbstverst\u00e4ndnis als \u201eFremde\u201c und \u201eG\u00e4ste\u201c auf Erden (Hebr 11,13; 1 Petr 2,11) geh\u00f6rt zum Selbstverst\u00e4ndnis der ersten Christen ebenso wie die Erfahrung der Diaspora. Wenn schlie\u00dflich im Hebr\u00e4erbrief (Hebr 13,2) die Gemeinde gemahnt wird: \u201eVergesst die Gastfreundschaft nicht; denn durch sie haben einige, ohne es zu ahnen, Engel beherbergt\u201c, wird hier nicht nur an das Fremdengesetz des AT angeschlossen, sondern auch das Risiko benannt, Fremde aufzunehmen. Denn vor der T\u00fcr dieser verfolgten Diasporagemeinde konnte auch ein r\u00f6mischer Soldat stehen. Es ist also keinesfalls harmlos, Fremde aufzunehmen \u2013 und dennoch in biblischer Tradition verpflichtend. Christus selbst begegnet im Fremden (Mt 25).<\/p>\n<p>Kern dieser Narrative ist regelm\u00e4\u00dfig die Erfahrung, dass Gott inmitten gr\u00f6\u00dfter Hoffnungslosigkeit neues Leben schaffen kann.<\/p>\n<p>Die biblischen Erz\u00e4hlungen k\u00f6nnen auch gelesen werden als Lerngeschichte im Kontext von Migration. Die dabei gewonnenen Erkenntnisse k\u00f6nnen vor allem in bedrohlichen Lebenssituationen immer wieder fruchtbar gemacht werden. Hier ist der Ort, an dem Hoffnung gelernt wird \u2013 durch Erinnerung, also Vergegenw\u00e4rtigung dessen, was die Vergangenheit f\u00fcr uns heute bedeutet.<\/p>\n<p>Was bedeutet das f\u00fcr uns?<\/p>\n<p>Die meisten von uns Christen in Europa geh\u00f6ren nicht zum Rand \u2013 wenngleich auch hierzulande bereits viel zu viele. Die meisten von uns leben auch nicht in katastrophischen Situationen. Dennoch f\u00fchlen sich viele von uns \u00fcberfordert, ohnm\u00e4chtig, hilflos und haben Angst vor den Ver\u00e4nderungen, die auf uns zukommen. Und das halte ich auch f\u00fcr&nbsp; angemessen. Auch ich f\u00fcrchte mich vor den kommenden Jahren. Mit historischer Vernunft betrachtet, geben die aktuellen Entwicklungen in der Weltpolitik, mit Blick auf Klimawandel, Armut und Terror wenig Grund zur Hoffnung.<\/p>\n<p>Aber die biblische Logik ist anders und an diese m\u00f6chte ich Sie heute, beim \u00dcbergang in das kommende Jahr erinnern. Die biblische Logik lebt aus der Hoffnung, die man gerade in so schwierigen Zeiten lernen kann, ja, die sich gerade hier bew\u00e4hren kann.<\/p>\n<p>Hoffnung meint hier nicht Optimismus, der ist wie der Pessimismus eine chronische Verstimmung. Hoffnung ist viel mehr. Hoffnung bedeutet psychologisch, auf der Basis an gute Erinnerungen aus der Vergangenheit schwierige Herausforderungen mit Zuversicht anzugehen. Solche Hoffnung kann \u2013 bedingt durch eine Kultur, in der es wenig Hoffnung gibt oder durch biographisches Schicksal schwach ausgepr\u00e4gt sein. Aber unsere Glaube mit seiner Lernschule der Hoffnung er\u00f6ffnet uns die M\u00f6glichkeit, unsere kleinen Hoffnungen in die gro\u00dfe Hoffnung der Heiligen Schrift einzuweben und mit ihr hoffen zu lernen. Hoffnung, das bedeute mit Thmoas von Aquin: In Zeiten der Krise die Orientierung an Gott beibehalten. Hoffnung dieser Art ist nicht blo\u00df ein Gef\u00fchl: Sie ist immer praktisch, sie handelt, sie wird widerst\u00e4ndig. Sie tr\u00e4gt der Wirklchkeit nicht die Schleppe nach, sondern die Fackel voran.<\/p>\n<p>Ich schlie\u00dfe mit einem Zitat aus Erga Migrantes, der gro\u00dfen Hoffnung auf die sich die Kirche bezieht, wenn sie auf die Migrationen blickt:<br \/>\n\u201eDie Fremden sind daher \u201eein sichtbares Zeichen und ein wirksamer Aufruf jenes Universalismus, der ein grundlegendes Element der katholischen Kirche ist. Eine \u201eVision\u201c&nbsp; des Jesaia k\u00fcndigte ihn an: \u201eAm Ende der Tage wird es geschehen: Der Berg mit dem Haus des Herrn steht fest gegr\u00fcndet als h\u00f6chster der Berge &#8230; Zu ihm str\u00f6men alle V\u00f6lker\u201c (Jes 2, 2). Im Evangelium sagt Jesus selbst voraus: \u201eMan wird von Osten und Westen und von Norden und S\u00fcden kommen und im Reich Gottes zu Tisch sitzen\u201c (Lk 13, 29), und in der Offenbarung des Johannes schaut man \u201eeine gro\u00dfe Schar aus allen Nationen und St\u00e4mmen, V\u00f6lkern und Sprachen\u201c (Offb 7, 9). Die Kirche ist jetzt auf einem m\u00fchsamen Weg zu diesem endg\u00fcltigen Ziel. Die Migrationen k\u00f6nnen wie ein Verweis auf diese gro\u00dfe Schar und eine Vorwegnahme der endg\u00fcltigen Begegnung der gesamten Menschheit mit Gott und in Gott sein.\u201c<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>Ausf\u00fchrliche Darstellung:<br \/>\nRegina Polak: Migration, Flucht und Religion. Praktisch-Theologische Beitr\u00e4ge, Ostfildern 2017, i.E.<\/p>\n<p><a href=\"http:\/\/www.vatican.va\/roman_curia\/pontifical_councils\/migrants\/documents\/rc_pc_migrants_doc_20040514_erga-migrantes-caritas-christi_ge.html\">&#8222;Erga migrantes caritas Christi&#8220; auf der Vatikan Website<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ansprache von Univ.Prof. Dr. Regina Polak im Jahresschluss-Gottesdienst am 31.12.2016 in der Pfarrkirche. Flucht und Migration: Ort, um Hoffnung zu lernen Ich danke f\u00fcr die Einladung, Gedanken zum Jahresabschluss formulieren zu d\u00fcrfen. Was sagt man am Ende eines weltweit schwierigen Jahres \u2013 zumal im Wissen, dass uns die kommenden Jahrzehnte vor unz\u00e4hlige Herausforderungen stellen werden? [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-4274","post","type-post","status-publish","format-standard","category-was-gewesen-ist"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:51:34","action":"category","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/posts\/4274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/comments?post=4274"}],"version-history":[{"count":3,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/posts\/4274\/revisions"}],"predecessor-version":[{"id":4277,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/posts\/4274\/revisions\/4277"}],"wp:attachment":[{"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/media?parent=4274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/categories?post=4274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/tags?post=4274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}