{"id":5447,"date":"2018-11-30T21:51:15","date_gmt":"2018-11-30T20:51:15","guid":{"rendered":"http:\/\/www.pfarregersthof.at\/komm\/?p=5447"},"modified":"2018-12-13T12:18:58","modified_gmt":"2018-12-13T11:18:58","slug":"dekanats-jugendadventvesper-9-12","status":"publish","type":"post","link":"https:\/\/www.pfarregersthof.at\/komm\/2018\/11\/dekanats-jugendadventvesper-9-12\/","title":{"rendered":"Dekanats-Jugendadventvesper (9.12.)"},"content":{"rendered":"<p>Herzliche Einladung zur Dekanats-Jugendadventvesper am Sonntag, 9.12.2018, um 19:00<\/p>\n<p>Ort: Jugendkeller der Pfarre St. Josef &#8211; Weinhaus (Gentzgasse 142).<\/p>\n<p>Eingeladen sind alle Jugendlichen, junge Erwachsenen, &#8230; die die Adventzeit mit Besinnung und mit einer kurzen Auszeit aus dem Alltagsstress beginnen m\u00f6chten.<br \/>\nAnschlie\u00dfend Begegnung bei Punsch, Tee und Keksen.<br \/>\n<span style=\"color: #3366ff;\"><em>Norbert Kaiser<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Herzliche Einladung zur Dekanats-Jugendadventvesper am Sonntag, 9.12.2018, um 19:00 Ort: Jugendkeller der Pfarre St. Josef &#8211; Weinhaus (Gentzgasse 142). Eingeladen sind alle Jugendlichen, junge Erwachsenen, &#8230; die die Adventzeit mit Besinnung und mit einer kurzen Auszeit aus dem Alltagsstress beginnen m\u00f6chten. Anschlie\u00dfend Begegnung bei Punsch, Tee und Keksen. Norbert Kaiser<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-5447","post","type-post","status-publish","format-standard","category-archiv"],"publishpress_future_action":{"enabled":false,"date":"2026-07-23 00:55:27","action":"category","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/posts\/5447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/comments?post=5447"}],"version-history":[{"count":1,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/posts\/5447\/revisions"}],"predecessor-version":[{"id":5448,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/posts\/5447\/revisions\/5448"}],"wp:attachment":[{"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/media?parent=5447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/categories?post=5447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pfarregersthof.at\/komm\/wp-json\/wp\/v2\/tags?post=5447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}